{"id":4407,"date":"2024-07-15T09:51:13","date_gmt":"2024-07-15T07:51:13","guid":{"rendered":"https:\/\/oup.local\/elastique-essentiel\/"},"modified":"2024-11-11T13:25:48","modified_gmt":"2024-11-11T11:25:48","slug":"elastique-essentiel","status":"publish","type":"book","link":"https:\/\/www.oup.es\/es\/elastique-essentiel\/","title":{"rendered":"\u00c9lastique Essentiel"},"featured_media":0,"template":"","badge":[611],"product-category":[3],"edition":[50,78],"level":[39],"stage":[11],"subject":[610],"product-type":[],"class_list":["post-4407","book","type-book","status-publish","hentry","badge-nouveaute","product-category-teaching","edition-andalucia","edition-nacional","level-cecr-a1-a1","stage-primary","subject-francais"],"acf":{"readers_products":false,"teaching_products":true,"supplementary_products":false,"subtitle_products":"","claim_products":"<strong>Ludique, agile et dynamique !<\/strong>","introduction_products":"Avec \u00c9lastique Essentiel, vos \u00e9l\u00e8ves apprendront \u00e0 <strong>communiquer de mani\u00e8re intuitive et ludique,<\/strong> gr\u00e2ce \u00e0 un <strong>enseignement flexible et personnalis\u00e9<\/strong> qui tient compte de la <strong>diversit\u00e9 en classe.\u00a0<\/strong>Tous les avantages de la m\u00e9thodologie d'Elastique, d\u00e9sormais disponibles pour des calendriers r\u00e9duits, avec une structure et un contenu adapt\u00e9s aux besoins uniques de vos \u00e9l\u00e8ves.","video_introduction":"","description_products":"","snippet_image_products":[14536],"snippet_summary_products":"M\u00e9thode de fran\u00e7ais langue \u00e9trang\u00e8re sur 2 niveaux","name_image_products":"","authors_products":"","isbn_products":false,"isbn_text_products":"","isbn_upload_products":13492,"number_of_pages_products":"","language_products":"","collection_products":"","collection_level_products":"","word_count_products":"","edition_text":"","especific_edition_avaible_products":"","timetable_products":"","niveaux_de_la_serie_products":"1 \u2013 2","edition_specifique_products":"ANDALOUSIE","aged_products":"","suggested_age_range_products":"","examns_products":"","series_consultant_products":"","series_editor_products":"","features_products":[{"feature_order_products":0,"feature_title_products":"Pourquoi choisir \u00c9lastique Essentiel ?","feature_text_products":"<ul>\r\n \t<li style=\"list-style-type: none;\">\r\n<ul>\r\n \t<li><strong>Une m\u00e9thode ludique. <\/strong>Avec <em>\u00c9lastique Essentiel<\/em> <strong>apprendre le fran\u00e7ais est un v\u00e9ritable plaisir<\/strong> car l\u2019apprentissage se fait par le jeu ! <strong>Les pages motivantes Coin r\u00e9cr\u00e9, <\/strong>apr\u00e8s les le\u00e7ons, permettent de consolider le vocabulaire et la grammaire de <strong>mani\u00e8re ludique et naturelle. <\/strong>D\u2019autre part, avec <strong>le Kit Actif gamifi\u00e9,<\/strong> les \u00e9l\u00e8ves ont acc\u00e8s \u00e0 un outil num\u00e9rique dynamique et innovateur qui inclut des jeux, des activit\u00e9s de langue ainsi que de comp\u00e9tences, et le tout avec la possibilit\u00e9 de gagner des diamants et des m\u00e9dailles !<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<ul>\r\n \t<li style=\"list-style-type: none;\">\r\n<ul>\r\n \t<li><strong>Une m\u00e9thode agile. <\/strong>La m\u00e9thode couvre les contenus essentiels de l\u2019apprentissage du fran\u00e7ais de mani\u00e8re efficace, avec <strong>des\u00a0le\u00e7ons courtes et bien structur\u00e9es,<\/strong> id\u00e9alement gradu\u00e9es et adapt\u00e9es aux besoins de vos \u00e9l\u00e8ves. <em>\u00c9lastique Essentiel<\/em> stimule les\u00a0strat\u00e9gies d\u2019apprentissage des \u00e9l\u00e8ves afin de les aider \u00e0 gagner en confiance, autonomie et progr\u00e8s.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<ul>\r\n \t<li style=\"list-style-type: none;\">\r\n<ul>\r\n \t<li><strong>Une m\u00e9thode dynamique.<\/strong> Gr\u00e2ce \u00e0 sa <strong>large palette de ressources multim\u00e9dias<\/strong> qui inclut des karaok\u00e9s, vid\u00e9os, flashcards\u00a0et bandes dessin\u00e9es anim\u00e9es, vous parviendrez \u00e0 \u00e9veiller au maximum la curiosit\u00e9 de vos \u00e9l\u00e8ves. <strong>L\u2019\u00e9quilibre parfait de la\u00a0m\u00e9thode entre activit\u00e9s de langue et activit\u00e9s ludiques<\/strong> vous permettra d\u2019off rir des le\u00e7ons dynamiques et motivantes \u00e0\u00a0vos \u00e9l\u00e8ves. Par ailleurs, la m\u00e9thode met en pratique une communication proche du r\u00e9el par le biais de petites productions\u00a0simples afi n de stimuler le d\u00e9sir d\u2019apprendre de vos \u00e9l\u00e8ves.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\n&nbsp;"},{"feature_order_products":1,"feature_title_products":"Qu\u2019est-ce qui le rend unique ?","feature_text_products":"Une <strong>solution hybride<\/strong> qui int\u00e8gre le format num\u00e9rique de chaque unit\u00e9 ainsi qu\u2019une <strong>grande quantit\u00e9 de ressources<\/strong> pour<strong> l\u2019enseignant<\/strong> et <strong>l\u2019apprenant.<\/strong>\r\n\r\n&nbsp;\r\n<ul>\r\n \t<li style=\"list-style-type: none;\">\r\n<ul>\r\n \t<li>Des ressources pour motiver les \u00e9l\u00e8ves et <strong>favoriser leur autonomie<\/strong> : club virtuel, posters interactifs, vid\u00e9os pour r\u00e9viser, karaok\u00e9s, jeux interactifs, bandes dessin\u00e9es anim\u00e9es...<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<ul>\r\n \t<li style=\"list-style-type: none;\">\r\n<ul>\r\n \t<li>Des outils pour <strong>faciliter la vie quotidienne des professeurs<\/strong> : suivi, devoirs personnalis\u00e9s, g\u00e9n\u00e9rateur de tests...<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\n&nbsp;"}],"related_product_products":null,"teaching_carousel_images_products":[13493,13494],"materials_carousel_images_products":null,"select_edition_products":[50,78],"selection_base":null,"text_libros_relacionados":"","libros_relacionados":"","subtitle_libros_relacionados":""},"_links":{"self":[{"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/book\/4407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/book"}],"about":[{"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/types\/book"}],"acf:term":[{"embeddable":true,"taxonomy":"edition","href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/edition\/78"},{"embeddable":true,"taxonomy":"edition","href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/edition\/50"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/media\/13494"},{"embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/media\/13493"},{"embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/media\/14536"}],"wp:attachment":[{"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/media?parent=4407"}],"wp:term":[{"taxonomy":"badge","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/badge?post=4407"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/product-category?post=4407"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/edition?post=4407"},{"taxonomy":"level","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/level?post=4407"},{"taxonomy":"stage","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/stage?post=4407"},{"taxonomy":"subject","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/subject?post=4407"},{"taxonomy":"product-type","embeddable":true,"href":"https:\/\/www.oup.es\/es\/wp-json\/wp\/v2\/product-type?post=4407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}